{"id":9350,"date":"2026-05-12T15:10:08","date_gmt":"2026-05-12T18:10:08","guid":{"rendered":"https:\/\/nordesteimprensa.com.br\/?p=9350"},"modified":"2026-05-12T15:10:09","modified_gmt":"2026-05-12T18:10:09","slug":"uniao-europeia-proibe-importacao-de-carnes-ovos-e-animais-do-brasil","status":"publish","type":"post","link":"https:\/\/nordesteimprensa.com.br\/index.php\/2026\/05\/12\/uniao-europeia-proibe-importacao-de-carnes-ovos-e-animais-do-brasil\/","title":{"rendered":"Uni\u00e3o Europeia pro\u00edbe importa\u00e7\u00e3o de carnes, ovos e animais do Brasil"},"content":{"rendered":"\n<p>A Uni\u00e3o Europeia (UE) retirou o Brasil da lista de pa\u00edses autorizados a exportar determinados produtos de origem animal para o bloco. A decis\u00e3o foi publicada nesta ter\u00e7a-feira, 12, e comunicada ao Minist\u00e9rio da Agricultura e Pecu\u00e1ria (Mapa). As novas restri\u00e7\u00f5es entram em vigor em 3 de setembro.<\/p>\n\n\n\n<p>Com a medida, ficam impedidas as exporta\u00e7\u00f5es de animais vivos destinados \u00e0 produ\u00e7\u00e3o de alimentos, al\u00e9m de produtos como carne bovina, aves, peixes, ovos, mel e equinos.<\/p>\n\n\n\n<p>Segundo o documento europeu, o Brasil n\u00e3o apresentou garantias consideradas suficientes sobre o controle e o uso de antimicrobianos na cria\u00e7\u00e3o de animais. A aus\u00eancia dessas informa\u00e7\u00f5es contraria as regras sanit\u00e1rias adotadas pela UE para limitar o uso de antibi\u00f3ticos na pecu\u00e1ria e reduzir riscos relacionados \u00e0 resist\u00eancia antimicrobiana.<\/p>\n\n\n\n<p>Apesar da exclus\u00e3o, o bloco europeu informou que o Brasil poder\u00e1 voltar a integrar a lista de pa\u00edses habilitados caso apresente as garantias exigidas pelas autoridades sanit\u00e1rias europeias.<\/p>\n\n\n\n<p>A rela\u00e7\u00e3o de pa\u00edses autorizados foi consolidada em 2024 e inclui na\u00e7\u00f5es como M\u00e9xico, Argentina e Col\u00f4mbia, mantidas por estarem, segundo a UE, em conformidade com os crit\u00e9rios estabelecidos.<\/p>\n\n\n\n<p>O an\u00fancio ocorre em meio \u00e0 entrada em vigor provis\u00f3ria do acordo de livre com\u00e9rcio entre Mercosul e Uni\u00e3o Europeia, iniciada em 1\u00ba de maio. Nos bastidores, a decis\u00e3o \u00e9 interpretada como um gesto pol\u00edtico voltado a agricultores e pecuaristas europeus que resistem ao tratado comercial por temor de aumento da concorr\u00eancia internacional.<\/p>\n\n\n\n<p>Fonte: Fanf1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Uni\u00e3o Europeia (UE) retirou o Brasil da lista de pa\u00edses autorizados a exportar determinados produtos de origem animal para o bloco. A decis\u00e3o foi publicada nesta ter\u00e7a-feira, 12, e comunicada ao Minist\u00e9rio da Agricultura e Pecu\u00e1ria (Mapa). As novas restri\u00e7\u00f5es entram em vigor em 3 de setembro. Com a medida, ficam impedidas as exporta\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-9350","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-theme-features"},"_links":{"self":[{"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9350"}],"version-history":[{"count":1,"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9350\/revisions"}],"predecessor-version":[{"id":9352,"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9350\/revisions\/9352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/media\/9351"}],"wp:attachment":[{"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nordesteimprensa.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}